{"id":69,"count":5,"description":"<span>Sie werden \u00fcber L\u00e4nder voller Geschichte, Denkm\u00e4ler und charakteristischer Calanchi fliegen. Entlang des Tanaro-Flusses werden wir am Horizont die Alpen, Mondov\u00ec und die Langhe sehen.<\/span>","link":"https:\/\/giroinmongolfiera.com\/de\/partenza_voli\/mondovi\/","name":"Mondov\u00ec","slug":"mondovi","taxonomy":"partenza_voli","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mondov\u00ec Archivi - Giro in mongolfiera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/giroinmongolfiera.com\/de\/partenza_voli\/mondovi\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mondov\u00ec Archivi - Giro in mongolfiera\" \/>\n<meta property=\"og:description\" content=\"Sorvolerai terre ricche di storia, monumenti e caratteristici calanchi. Seguendo il corso del fiume Tanaro vedremo all\u2019orizzonte le Alpi, Mondov\u00ec e le Langhe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/giroinmongolfiera.com\/de\/partenza_voli\/mondovi\/\" \/>\n<meta property=\"og:site_name\" content=\"Giro in mongolfiera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/giroinmongolfiera.com\\\/partenza_voli\\\/mondovi\\\/\",\"url\":\"https:\\\/\\\/giroinmongolfiera.com\\\/partenza_voli\\\/mondovi\\\/\",\"name\":\"Mondov\u00ec Archivi - Giro in mongolfiera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giroinmongolfiera.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/giroinmongolfiera.com\\\/partenza_voli\\\/mondovi\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/giroinmongolfiera.com\\\/partenza_voli\\\/mondovi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/giroinmongolfiera.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mondov\u00ec\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/giroinmongolfiera.com\\\/#website\",\"url\":\"https:\\\/\\\/giroinmongolfiera.com\\\/\",\"name\":\"Giro in mongolfiera\",\"description\":\"Vola in mongolfiera, vivi un&#039;esperienza unica\",\"publisher\":{\"@id\":\"https:\\\/\\\/giroinmongolfiera.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/giroinmongolfiera.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/giroinmongolfiera.com\\\/#organization\",\"name\":\"Giroinmongolfiera SRL\",\"url\":\"https:\\\/\\\/giroinmongolfiera.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/giroinmongolfiera.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/giroinmongolfiera.com\\\/wp-content\\\/uploads\\\/Giro_in_Mongolfiera-LOGO.png\",\"contentUrl\":\"https:\\\/\\\/giroinmongolfiera.com\\\/wp-content\\\/uploads\\\/Giro_in_Mongolfiera-LOGO.png\",\"width\":385,\"height\":126,\"caption\":\"Giroinmongolfiera SRL\"},\"image\":{\"@id\":\"https:\\\/\\\/giroinmongolfiera.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mondov\u00ec Archivi - Giro in mongolfiera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/giroinmongolfiera.com\/de\/partenza_voli\/mondovi\/","og_locale":"de_DE","og_type":"article","og_title":"Mondov\u00ec Archivi - Giro in mongolfiera","og_description":"Sorvolerai terre ricche di storia, monumenti e caratteristici calanchi. Seguendo il corso del fiume Tanaro vedremo all\u2019orizzonte le Alpi, Mondov\u00ec e le Langhe.","og_url":"https:\/\/giroinmongolfiera.com\/de\/partenza_voli\/mondovi\/","og_site_name":"Giro in mongolfiera","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/giroinmongolfiera.com\/partenza_voli\/mondovi\/","url":"https:\/\/giroinmongolfiera.com\/partenza_voli\/mondovi\/","name":"Mondov\u00ec Archivi - Giro in mongolfiera","isPartOf":{"@id":"https:\/\/giroinmongolfiera.com\/#website"},"breadcrumb":{"@id":"https:\/\/giroinmongolfiera.com\/partenza_voli\/mondovi\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/giroinmongolfiera.com\/partenza_voli\/mondovi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/giroinmongolfiera.com\/"},{"@type":"ListItem","position":2,"name":"Mondov\u00ec"}]},{"@type":"WebSite","@id":"https:\/\/giroinmongolfiera.com\/#website","url":"https:\/\/giroinmongolfiera.com\/","name":"Giro in mongolfiera","description":"Vola in mongolfiera, vivi un&#039;esperienza unica","publisher":{"@id":"https:\/\/giroinmongolfiera.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/giroinmongolfiera.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/giroinmongolfiera.com\/#organization","name":"Giroinmongolfiera SRL","url":"https:\/\/giroinmongolfiera.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/giroinmongolfiera.com\/#\/schema\/logo\/image\/","url":"https:\/\/giroinmongolfiera.com\/wp-content\/uploads\/Giro_in_Mongolfiera-LOGO.png","contentUrl":"https:\/\/giroinmongolfiera.com\/wp-content\/uploads\/Giro_in_Mongolfiera-LOGO.png","width":385,"height":126,"caption":"Giroinmongolfiera SRL"},"image":{"@id":"https:\/\/giroinmongolfiera.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/giroinmongolfiera.com\/de\/wp-json\/wp\/v2\/partenza_voli\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giroinmongolfiera.com\/de\/wp-json\/wp\/v2\/partenza_voli"}],"about":[{"href":"https:\/\/giroinmongolfiera.com\/de\/wp-json\/wp\/v2\/taxonomies\/partenza_voli"}],"wp:post_type":[{"href":"https:\/\/giroinmongolfiera.com\/de\/wp-json\/wp\/v2\/product?partenza_voli=69"},{"href":"https:\/\/giroinmongolfiera.com\/de\/wp-json\/wp\/v2\/pacchetto_volo?partenza_voli=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}